{"id":3871,"date":"2022-12-19T15:27:12","date_gmt":"2022-12-19T14:27:12","guid":{"rendered":"https:\/\/www.ch-fecamp.fr\/?p=3871"},"modified":"2022-12-19T15:27:13","modified_gmt":"2022-12-19T14:27:13","slug":"conseil-de-vie-sociale-cvs-commun-aux-4-ehpad","status":"publish","type":"post","link":"https:\/\/www.ch-fecamp.fr\/index.php\/2022\/12\/19\/conseil-de-vie-sociale-cvs-commun-aux-4-ehpad\/","title":{"rendered":"Conseil de Vie Sociale (CVS) commun aux 4 EHPAD"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Ce vendredi 16 d\u00e9cembre 2022, s\u2019est tenu un Conseil de Vie Sociale (CVS) commun aux 4 EHPAD du CH de F\u00e9camp.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Ce CVS pilot\u00e9 par Monsieur LEFEVRE, Directeur G\u00e9n\u00e9ral, Monsieur DAVY, Directeur des Soins ainsi que des Pr\u00e9sidents des CVS, a pour but de mettre en avant les actions communes men\u00e9es tout au long de l&rsquo;ann\u00e9e (secteurs techniques, logistiques, animation, qualit\u00e9, entre autres).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>La Direction a notamment \u00e9voqu\u00e9 la crise sanitaire, la vaccination des r\u00e9sidents, l&rsquo;actualisation de la coupe PATHOS et en a profit\u00e9 pour remercier l&rsquo;ensemble des \u00e9quipes qui participent \u00e0 l&rsquo;accompagnement, \u00e0 la prise en charge et au bien-\u00eatre des r\u00e9sidents au quotidien.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"360\" height=\"480\" src=\"https:\/\/www.ch-fecamp.fr\/wp-content\/uploads\/2022\/12\/4329441515916855842.jpg\" alt=\"\" data-id=\"3872\" data-full-url=\"https:\/\/www.ch-fecamp.fr\/wp-content\/uploads\/2022\/12\/4329441515916855842.jpg\" data-link=\"https:\/\/www.ch-fecamp.fr\/?attachment_id=3872\" class=\"wp-image-3872\" srcset=\"https:\/\/www.ch-fecamp.fr\/wp-content\/uploads\/2022\/12\/4329441515916855842.jpg 360w, https:\/\/www.ch-fecamp.fr\/wp-content\/uploads\/2022\/12\/4329441515916855842-225x300.jpg 225w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"480\" height=\"640\" src=\"https:\/\/www.ch-fecamp.fr\/wp-content\/uploads\/2022\/12\/515078859273348281.jpg\" alt=\"\" data-id=\"3873\" data-full-url=\"https:\/\/www.ch-fecamp.fr\/wp-content\/uploads\/2022\/12\/515078859273348281.jpg\" data-link=\"https:\/\/www.ch-fecamp.fr\/?attachment_id=3873\" class=\"wp-image-3873\" srcset=\"https:\/\/www.ch-fecamp.fr\/wp-content\/uploads\/2022\/12\/515078859273348281.jpg 480w, https:\/\/www.ch-fecamp.fr\/wp-content\/uploads\/2022\/12\/515078859273348281-225x300.jpg 225w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"480\" height=\"360\" src=\"https:\/\/www.ch-fecamp.fr\/wp-content\/uploads\/2022\/12\/1022464739048617360.jpg\" alt=\"\" data-id=\"3874\" data-full-url=\"https:\/\/www.ch-fecamp.fr\/wp-content\/uploads\/2022\/12\/1022464739048617360.jpg\" data-link=\"https:\/\/www.ch-fecamp.fr\/?attachment_id=3874\" class=\"wp-image-3874\" srcset=\"https:\/\/www.ch-fecamp.fr\/wp-content\/uploads\/2022\/12\/1022464739048617360.jpg 480w, https:\/\/www.ch-fecamp.fr\/wp-content\/uploads\/2022\/12\/1022464739048617360-300x225.jpg 300w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"480\" height=\"640\" src=\"https:\/\/www.ch-fecamp.fr\/wp-content\/uploads\/2022\/12\/4061398434993722777.jpg\" alt=\"\" data-id=\"3875\" data-full-url=\"https:\/\/www.ch-fecamp.fr\/wp-content\/uploads\/2022\/12\/4061398434993722777.jpg\" data-link=\"https:\/\/www.ch-fecamp.fr\/?attachment_id=3875\" class=\"wp-image-3875\" srcset=\"https:\/\/www.ch-fecamp.fr\/wp-content\/uploads\/2022\/12\/4061398434993722777.jpg 480w, https:\/\/www.ch-fecamp.fr\/wp-content\/uploads\/2022\/12\/4061398434993722777-225x300.jpg 225w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><\/figure><\/li><\/ul><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Ce vendredi 16 d\u00e9cembre 2022, s\u2019est tenu un Conseil de Vie Sociale (CVS) commun aux 4 EHPAD du CH de F\u00e9camp. Ce CVS pilot\u00e9 par Monsieur LEFEVRE, Directeur G\u00e9n\u00e9ral, Monsieur DAVY, Directeur des Soins ainsi que des Pr\u00e9sidents des CVS, a pour but de mettre en avant les actions communes men\u00e9es tout au long de [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":3874,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-3871","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/www.ch-fecamp.fr\/index.php\/wp-json\/wp\/v2\/posts\/3871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ch-fecamp.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ch-fecamp.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ch-fecamp.fr\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ch-fecamp.fr\/index.php\/wp-json\/wp\/v2\/comments?post=3871"}],"version-history":[{"count":1,"href":"https:\/\/www.ch-fecamp.fr\/index.php\/wp-json\/wp\/v2\/posts\/3871\/revisions"}],"predecessor-version":[{"id":3876,"href":"https:\/\/www.ch-fecamp.fr\/index.php\/wp-json\/wp\/v2\/posts\/3871\/revisions\/3876"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ch-fecamp.fr\/index.php\/wp-json\/wp\/v2\/media\/3874"}],"wp:attachment":[{"href":"https:\/\/www.ch-fecamp.fr\/index.php\/wp-json\/wp\/v2\/media?parent=3871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ch-fecamp.fr\/index.php\/wp-json\/wp\/v2\/categories?post=3871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ch-fecamp.fr\/index.php\/wp-json\/wp\/v2\/tags?post=3871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}